{"id":3681,"date":"2022-11-16T16:59:00","date_gmt":"2022-11-16T15:59:00","guid":{"rendered":"https:\/\/www2.uffective.com\/2022\/11\/16\/what-are-similarity-predictions\/"},"modified":"2026-03-30T19:25:24","modified_gmt":"2026-03-30T17:25:24","slug":"what-are-similarity-predictions","status":"publish","type":"post","link":"https:\/\/www.uffective.com\/de\/what-are-similarity-predictions\/","title":{"rendered":"Was sind \u00c4hnlichkeitsvorhersagen?"},"content":{"rendered":"\n<p><strong>Unser Team f\u00fcr maschinelles Lernen hat ein neues Produkt entwickelt, um \u00e4hnliche Artikel in Uffective automatisch zu identifizieren. Dieses Wort-Vektor-Modell wird bereits von einigen unserer gr\u00f6\u00dften Kunden verwendet.<\/strong><\/p>\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div style=\"height:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-media-text alignfull is-stacked-on-mobile has-background\" style=\"background-color:#f3f3f3;grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"850\" height=\"680\" src=\"\/wp-content\/uploads\/2022\/12\/Blog_Interview_Niels.png\" alt=\"\" class=\"wp-image-3274 size-full\" srcset=\"\/wp-content\/uploads\/2022\/12\/Blog_Interview_Niels.png 850w, \/wp-content\/uploads\/2022\/12\/Blog_Interview_Niels-300x240.png 300w, \/wp-content\/uploads\/2022\/12\/Blog_Interview_Niels-768x614.png 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><strong>Niels van der Pas | Direktor f\u00fcr Maschinelles Lernen bei Uffective<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\">&#8222;Der Vorteil dieser Modelle ist, dass sie die Effizienz bei der Durchf\u00fchrung von Projekten erh\u00f6hen k\u00f6nnen.<\/p>\n<\/div><\/div>\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\"><strong>Welchen Vorteil hat die \u00c4hnlichkeitsvorhersage f\u00fcr mich als Uffective-Nutzer?<\/strong><\/h2>\n\n<p>Die Modelle, mit denen Uffective arbeitet, k\u00f6nnen vorhersagen, wie \u00e4hnlich Ihre Projekte, OKRs und\/oder User Stories sind. <\/p>\n\n<p>Wenn zum Beispiel ein Projekt in Deutschland durchgef\u00fchrt wird und ein sehr \u00e4hnliches Projekt vor einem Jahr in Schweden durchgef\u00fchrt wurde, kann das Projektteam in Deutschland viel von dem schwedischen Projektleiter lernen. Dies kann die Durchf\u00fchrung des deutschen Projekts effizienter machen, aber es ist auch m\u00f6glich, bessere Ergebnisse zu erzielen, weil das Projektteam \u00fcber mehr Vorinformationen verf\u00fcgt.<\/p>\n\n<p>Das Gleiche gilt f\u00fcr die Effizienz von OKRs und User Stories. Auch hier erm\u00f6glicht es die \u00c4hnlichkeitsvorhersage, von Kollegen mit \u00e4hnlichen User Stories und OKRs zu profitieren. Again, similarity prediction allows you to benefit from colleagues with similar user stories and OKRs. <\/p>\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\"><strong>Welche<\/strong> Auswirkungen haben \u00c4hnlichkeitsprognosen?<\/h2>\n\n<p>Einige unserer Kunden schreiben die Wiederverwendung gro\u00df, da sie Investitionen in ihrem Unternehmen nutzen wollen. Zu Beginn dieses Jahres haben wir f\u00fcr jedes Projekt die M\u00f6glichkeit geschaffen, die \u00e4hnlichsten Projekte zu finden. Da sich nicht jeder die Zeit nimmt, nach \u00e4hnlichen Investitionen zu suchen, weil es &#8222;einfach nicht in der DNA eines Projektleiters liegt&#8220;, haben wir die Wiederverwendung in die Uffecte-Prozesse integriert.<\/p>\n\n<p><strong>Wie?<\/strong><\/p>\n\n<p>Unser Assistent informiert einen Benutzer, der ein neues Projekt anlegt, direkt nach der Eingabe dieser Investition in Uffective \u00fcber die \u00e4hnlichsten Investitionen, also bevor das Team wirklich mit der Arbeit daran beginnt. Wir unterst\u00fctzen aber auch die F\u00fchrungsebene, indem wir die sechs \u00e4hnlichsten Investitionen in die von Uffective generierten Verwaltungsratsvorschl\u00e4ge aufnehmen. Auf diese Weise k\u00f6nnen F\u00fchrungskr\u00e4fte in Italien auch die \u00e4hnlichsten Investitionen in Deutschland, den Niederlanden oder dem Vereinigten K\u00f6nigreich sehen.<\/p>\n\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Unser Team f\u00fcr maschinelles Lernen hat ein neues Produkt entwickelt, um \u00e4hnliche Artikel in Uffective automatisch zu identifizieren. Dieses Wort-Vektor-Modell wird bereits von einigen unserer gr\u00f6\u00dften Kunden verwendet. Niels van der Pas | Direktor f\u00fcr Maschinelles Lernen bei Uffective &#8222;Der Vorteil dieser Modelle ist, dass sie die Effizienz bei der Durchf\u00fchrung von Projekten erh\u00f6hen k\u00f6nnen. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3427,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","rank_math_focus_keyword":"\u00c4hnlichkeitsvorhersagen KI PPM","rank_math_description":"\u00c4hnlichkeitsvorhersagen in Uffective: Wie KI aus historischen Projektdaten lernt und pr\u00e4zise Prognosen f\u00fcr neue Projekte erstellt.","rank_math_title":"Was sind \u00c4hnlichkeitsvorhersagen? KI im Projektmanagement","footnotes":""},"categories":[41,37,40],"tags":[],"class_list":["post-3681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-machine-learning-de","category-portfolio-de","category-strategie"],"_links":{"self":[{"href":"https:\/\/www.uffective.com\/de\/wp-json\/wp\/v2\/posts\/3681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uffective.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uffective.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uffective.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uffective.com\/de\/wp-json\/wp\/v2\/comments?post=3681"}],"version-history":[{"count":3,"href":"https:\/\/www.uffective.com\/de\/wp-json\/wp\/v2\/posts\/3681\/revisions"}],"predecessor-version":[{"id":6760,"href":"https:\/\/www.uffective.com\/de\/wp-json\/wp\/v2\/posts\/3681\/revisions\/6760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uffective.com\/de\/wp-json\/wp\/v2\/media\/3427"}],"wp:attachment":[{"href":"https:\/\/www.uffective.com\/de\/wp-json\/wp\/v2\/media?parent=3681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uffective.com\/de\/wp-json\/wp\/v2\/categories?post=3681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uffective.com\/de\/wp-json\/wp\/v2\/tags?post=3681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}